{"id":260,"count":8,"description":"","link":"https:\/\/amicolive.com\/liver\/category\/bigolive\/","name":"BIGO\u30e9\u30a4\u30d6\u306b\u3064\u3044\u3066","slug":"bigolive","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/amicolive.com\/liver\/wp-json\/wp\/v2\/categories\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amicolive.com\/liver\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/amicolive.com\/liver\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/amicolive.com\/liver\/wp-json\/wp\/v2\/posts?categories=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}